{"id":14401,"date":"2024-07-28T21:52:28","date_gmt":"2024-07-29T01:52:28","guid":{"rendered":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg"},"modified":"2026-04-23T22:54:05","modified_gmt":"2026-04-24T02:54:05","slug":"baltars-plate-012s-inuit-suta","status":"inherit","type":"attachment","link":"https:\/\/antiqueref.com\/index.php\/soviet-porcelain\/baltars\/baltars-plate-012s-inuit-suta\/","title":{"rendered":"Baltars porcelain plate by Suta &#8220;Inuit&#8221;"},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"class_list":["post-14401","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-1000x1000.jpg\" class=\"attachment-medium size-medium\" alt=\"Baltars Plate 012s Inuit Suta\" srcset=\"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-1000x1000.jpg 1000w, https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-1024x1024.jpg 1024w, https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-300x300.jpg 300w, https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-768x768.jpg 768w, https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-600x600.jpg 600w, https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg 1531w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"TyKEzUkAAr\"><p><a href=\"https:\/\/antiqueref.com\/index.php\/soviet-porcelain\/baltars\/romans-suta\/\">Romans Suta (1896-1944)<\/a><\/p><\/blockquote>\n<p><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; visibility: hidden;\" title=\"&#8220;Romans Suta (1896-1944)&#8221; &#8212; AntiqueRef\" src=\"https:\/\/antiqueref.com\/index.php\/soviet-porcelain\/baltars\/romans-suta\/embed\/#?secret=0olTOd9ABd#?secret=TyKEzUkAAr\" data-secret=\"TyKEzUkAAr\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/p>\n"},"caption":{"rendered":"<p>Suta &#8211; Inuit<\/p>\n"},"alt_text":"Baltars Plate 012s Inuit Suta","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1531,"height":1531,"file":"2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg","filesize":1048886,"sizes":{"medium":{"file":"Baltars-plate-012s-Inuit-Suta-1000x1000.jpg","width":1000,"height":1000,"filesize":137889,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-1000x1000.jpg"},"large":{"file":"Baltars-plate-012s-Inuit-Suta-1024x1024.jpg","width":1024,"height":1024,"filesize":142317,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-1024x1024.jpg"},"thumbnail":{"file":"Baltars-plate-012s-Inuit-Suta-300x300.jpg","width":300,"height":300,"filesize":22575,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-300x300.jpg"},"medium_large":{"file":"Baltars-plate-012s-Inuit-Suta-768x768.jpg","width":768,"height":768,"filesize":93721,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-768x768.jpg"},"store-sq-thumb":{"file":"Baltars-plate-012s-Inuit-Suta-600x600.jpg","width":600,"height":600,"filesize":64828,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-600x600.jpg"},"store-thumb":{"file":"Baltars-plate-012s-Inuit-Suta-540x450.jpg","width":540,"height":450,"filesize":50256,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-540x450.jpg"},"pop-thumb":{"file":"Baltars-plate-012s-Inuit-Suta-542x340.jpg","width":542,"height":340,"filesize":39040,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta-542x340.jpg"},"full":{"file":"Baltars-plate-012s-Inuit-Suta.jpg","width":1531,"height":1531,"mime_type":"image\/jpeg","source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"1","keywords":[]}},"post":14375,"source_url":"https:\/\/antiqueref.com\/wp-content\/uploads\/2024\/07\/Baltars-plate-012s-Inuit-Suta.jpg","filename":"Baltars-plate-012s-Inuit-Suta.jpg","filesize":1048886,"_links":{"self":[{"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/media\/14401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/comments?post=14401"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/categories?post=14401"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/tags?post=14401"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":14375,"href":"https:\/\/antiqueref.com\/index.php\/wp-json\/wp\/v2\/pages\/14375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}